{"id":540,"date":"2019-02-08T19:59:47","date_gmt":"2019-02-08T16:59:47","guid":{"rendered":"https:\/\/mycarrentals.gr\/mystras-2\/"},"modified":"2023-03-09T11:50:09","modified_gmt":"2023-03-09T08:50:09","slug":"mystras-2","status":"publish","type":"post","link":"https:\/\/mycarrentals.gr\/de\/mystras-2\/","title":{"rendered":"Autovermietung Mystras"},"content":{"rendered":"<h2>Mystras Autovermietung<\/h2>\n<p>Sie suchen den besten Mietwagenservice in\u00a0<strong>Mystras<\/strong>\u00a0?\u00a0<em>My car rentals<\/em>\u00a0bietet die besten Autovermietungen zu vern\u00fcnftigen Preisen<\/p>\n<p>Nachfragen\u00a0<a href=\"https:\/\/mycarrentals.gr\/de\/rent-a-car-now\/\">Mystras autovermietung<\/a><\/p>\n<p><iframe style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d6366.973349134456!2d22.371507727441475!3d37.06971413015722!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x1361cc1072536ff3%3A0x400bd2ce2b99120!2zzpzPhc-Dz4TPgc6sz4IgMjMxIDAw!5e0!3m2!1sel!2sgr!4v1676637612960!5m2!1sel!2sgr\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Mystras bzw. Mistra (griechisch \u039c\u03c5\u03c3\u03c4\u03c1\u03ac\u03c2) ist eine byzantinische Ruinenstadt in der N\u00e4he des gleichnamigen Dorfes in Griechenland, nordwestlich von Sparta auf einem H\u00fcgel im Vorfeld des Taygetos-Gebirges.<\/p>\n<p>Die Kirchen von Mystras sind im sogenannten Mystras-Typus errichtet, der teils als Verbindung von westlich-lateinischen und byzantinischen Bauformen gedeutet wird: Auf eine Basilika wurde ein zweites Geschoss in Form einer Kreuzkuppelkirche gesetzt. Die Hauptkirche (die Mitropolis) liegt auf einem etwa 600 m hohen Berg und steht \u2013 wie alle Geb\u00e4ude der Stadt \u2013 unter Denkmalschutz. Ber\u00fchmt ist daneben auch die Kirche des fr\u00fcheren Peribleptos-Klosters, die teilweise in eine Felsgrotte (die Demeterh\u00f6hle, die in der Antike wohl ein heidnisches Heiligtum war) hineingebaut und wie viele andere Kirchen der Stadt reich mit byzantinischen Fresken verziert wurde.<\/p>\n<p>1989 wurde Mystras von der UNESCO in die Liste der Denkm\u00e4ler des Weltkulturerbes aufgenommen. Der Despotenpalast wird derzeit (2013) umfassend restauriert.<\/p>\n<p>Goethe, der selbst niemals Griechenland bereiste, setzte Mystras ein literarisches Denkmal, indem er sich von Berichten \u00fcber die Stadt zur Schilderung jener Kreuzfahrerfestung bei Sparta inspirieren lie\u00df, auf der Faust die sch\u00f6ne Helena trifft.<\/p>\n<p>Quelle: wikipedia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mystras Autovermietung Sie suchen den besten Mietwagenservice in\u00a0Mystras\u00a0?\u00a0My car rentals\u00a0bietet die besten Autovermietungen zu vern\u00fcnftigen Preisen Nachfragen\u00a0Mystras autovermietung Mystras bzw. Mistra (griechisch \u039c\u03c5\u03c3\u03c4\u03c1\u03ac\u03c2) ist eine byzantinische Ruinenstadt in der N\u00e4he des gleichnamigen Dorfes in Griechenland, nordwestlich von Sparta auf einem H\u00fcgel im Vorfeld des Taygetos-Gebirges. Die Kirchen von Mystras sind im sogenannten Mystras-Typus errichtet, der [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[16],"tags":[],"class_list":["post-540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reiseziele"],"_links":{"self":[{"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/posts\/540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/comments?post=540"}],"version-history":[{"count":0,"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/posts\/540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/media\/537"}],"wp:attachment":[{"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/media?parent=540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/categories?post=540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mycarrentals.gr\/de\/wp-json\/wp\/v2\/tags?post=540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}